{"id":9908,"date":"2020-01-12T17:16:02","date_gmt":"2020-01-12T17:16:02","guid":{"rendered":"https:\/\/t03.divertarte.com\/?post_type=product&#038;p=9908"},"modified":"2023-10-10T16:43:27","modified_gmt":"2023-10-10T15:43:27","slug":"glicerina-branca-para-sabonetes-250-gr","status":"publish","type":"product","link":"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/","title":{"rendered":"Glicerina Branca para sabonetes 250 gr"},"content":{"rendered":"<p>Glicerina para Sabonetes vegetal base Branca 250 gr. Base de Glicerina Branca em Portugal 250 g aprox<br \/>\nGlicerina em Barra, Glicerina Vegetal, Base glicerinada branca opaca para sabonetes,<br \/>\nGlicerina vegetal para sabonetes, Glicerina s\u00f3lida, Glicerina.<br \/>\nJ\u00e1 sabes onde comprar glicerina para Sabonetes comprar em Portugal, \u00e9 na Divertarte.<\/p>\n<p>O Sab\u00e3o base de glicerina branco \u00e9 uma base opaca de sab\u00e3o (derreter e verter) portanto serve para fazer sabonete artesanal caseiro de uma forma f\u00e1cil e r\u00e1pida com uns resultados extraordin\u00e1rios.<\/p>\n<p>Al\u00e9m disso este tipo de sab\u00e3o est\u00e1 formulado para que possas derreter e adicionar ess\u00eancias, corantes ou princ\u00edpios activos para fazer sabonetes \u00fanicos e exclusivos.<br \/>\nPara obter cores mais firmes em vez de corante adicione pigmento<\/p>\n<p><em>Produto hidratante, hipoalerg\u00e9nico e n\u00e3o toxico.<\/em><\/p>\n<p><em>Utiliza-se para fazer sabonetes artesanais.\u00a0<\/em><\/p>\n<p><span id=\"result_box\" class=\"\" lang=\"pt\"><em><span class=\"hps\">Caracter\u00edsticas:\u00a0<\/span><\/em><em><span class=\"hps\">Tudo \u00e0 base de vegetais,\u00a0<\/span><\/em><em><span class=\"hps\">Boa<\/span>\u00a0<span class=\"hps\">forma\u00e7\u00e3o de espuma,\u00a0<\/span><\/em><em><span class=\"hps\">Boa<\/span>\u00a0<span class=\"hps\">hidrata\u00e7\u00e3o\u00a0<\/span><span class=\"hps\">de<\/span>\u00a0<span class=\"hps\">um alto teor<\/span>\u00a0<span class=\"hps\">de glicerina, portanto\u00a0<\/span><span class=\"hps\">proporciona uma<\/span>\u00a0<span class=\"hps\">agrad\u00e1vel\u00a0<\/span><span class=\"hps\">sensa\u00e7\u00e3o na<\/span>\u00a0<span class=\"hps\">pele,\u00a0<\/span><\/em><em><span class=\"hps\">O<\/span><span class=\"hps\">dor<\/span>\u00a0<span class=\"hps\">neutro.\u00a0<\/span><\/em><em><span class=\"hps\">Proporciona excelente<\/span>\u00a0<span class=\"hps\">assimila\u00e7\u00e3o da\u00a0<\/span><span class=\"hps\">fragr\u00e2ncia,\u00a0<\/span><\/em><em><span class=\"hps\">PH<\/span>\u00a0<span class=\"hps\">7,5-8,5,\u00a0<\/span><\/em><em><span class=\"hps\">Indicado para<\/span>\u00a0<span class=\"hps\">corte\u00a0<\/span><span class=\"hps\">ou moldagem<\/span><span class=\"\">.<\/span><\/em><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Glicerina Vegetal para Sabonetes base Branca 250 gr<\/p>\n<p>O Sab\u00e3o base de glicerina branco \u00e9 uma base opaca de sab\u00e3o (derreter e verter) para fazer sabonete artesanal caseiro de uma forma f\u00e1cil e r\u00e1pida com uns resultados extraordin\u00e1rios. Este tipo de sab\u00e3o est\u00e1 preparado para que possas derreter e adicionar ess\u00eancias, corantes ou princ\u00edpios activos para fazer sabonetes \u00fanicos e exclusivos.<br \/>\nPara obter cores mais firmes em vez de corante adicione Pigmento.<\/p>\n","protected":false},"featured_media":9909,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[385,58,381,15],"product_tag":[1054],"class_list":["post-9908","product","type-product","status-publish","has-post-thumbnail","product_cat-bases-de-glicerina","product_cat-glicerina-para-sabonetes","product_cat-materiais-para-sabonetes","product_cat-ver-todos-os-produtos","product_tag-glicerina-branca","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Glicerina Branca para sabonetes 250 gr - div0-staging<\/title>\n<meta name=\"description\" content=\"Glicerina para Sabonetes vegetal base Branca 250 g. Base de Glicerina Branca em Portugal Glicerina vegetal para sabonetes, Glicerina s\u00f3lida\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glicerina Branca para sabonetes 250 gr - div0-staging\" \/>\n<meta property=\"og:description\" content=\"Glicerina para Sabonetes vegetal base Branca 250 g. Base de Glicerina Branca em Portugal Glicerina vegetal para sabonetes, Glicerina s\u00f3lida\" \/>\n<meta property=\"og:url\" content=\"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/\" \/>\n<meta property=\"og:site_name\" content=\"div0-staging\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T15:43:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/t03.divertarte.com\/wp-content\/uploads\/2020\/01\/glicerina-branca-250g..jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/index.php\\\/produto\\\/glicerina-branca-para-sabonetes-250-gr\\\/\",\"url\":\"https:\\\/\\\/t03.divertarte.com\\\/index.php\\\/produto\\\/glicerina-branca-para-sabonetes-250-gr\\\/\",\"name\":\"Glicerina Branca para sabonetes 250 gr - div0-staging\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/index.php\\\/produto\\\/glicerina-branca-para-sabonetes-250-gr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/index.php\\\/produto\\\/glicerina-branca-para-sabonetes-250-gr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/t03.divertarte.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/glicerina-branca-250g..jpg\",\"datePublished\":\"2020-01-12T17:16:02+00:00\",\"dateModified\":\"2023-10-10T15:43:27+00:00\",\"description\":\"Glicerina para Sabonetes vegetal base Branca 250 g. Base de Glicerina Branca em Portugal Glicerina vegetal para sabonetes, Glicerina s\u00f3lida\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/index.php\\\/produto\\\/glicerina-branca-para-sabonetes-250-gr\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/t03.divertarte.com\\\/index.php\\\/produto\\\/glicerina-branca-para-sabonetes-250-gr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/index.php\\\/produto\\\/glicerina-branca-para-sabonetes-250-gr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/t03.divertarte.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/glicerina-branca-250g..jpg\",\"contentUrl\":\"https:\\\/\\\/t03.divertarte.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/glicerina-branca-250g..jpg\",\"width\":400,\"height\":400,\"caption\":\"glicerina para sabonetes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/index.php\\\/produto\\\/glicerina-branca-para-sabonetes-250-gr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/t03.divertarte.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/t03.divertarte.com\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Glicerina Branca para sabonetes 250 gr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/#website\",\"url\":\"https:\\\/\\\/t03.divertarte.com\\\/\",\"name\":\"Divertarte\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/t03.divertarte.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/#organization\",\"name\":\"Divertarte\",\"url\":\"https:\\\/\\\/t03.divertarte.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/t03.divertarte.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-div.jpg\",\"contentUrl\":\"https:\\\/\\\/t03.divertarte.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-div.jpg\",\"width\":295,\"height\":123,\"caption\":\"Divertarte\"},\"image\":{\"@id\":\"https:\\\/\\\/t03.divertarte.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Glicerina Branca para sabonetes 250 gr - div0-staging","description":"Glicerina para Sabonetes vegetal base Branca 250 g. Base de Glicerina Branca em Portugal Glicerina vegetal para sabonetes, Glicerina s\u00f3lida","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"Glicerina Branca para sabonetes 250 gr - div0-staging","og_description":"Glicerina para Sabonetes vegetal base Branca 250 g. Base de Glicerina Branca em Portugal Glicerina vegetal para sabonetes, Glicerina s\u00f3lida","og_url":"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/","og_site_name":"div0-staging","article_modified_time":"2023-10-10T15:43:27+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/t03.divertarte.com\/wp-content\/uploads\/2020\/01\/glicerina-branca-250g..jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/","url":"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/","name":"Glicerina Branca para sabonetes 250 gr - div0-staging","isPartOf":{"@id":"https:\/\/t03.divertarte.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/#primaryimage"},"image":{"@id":"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/#primaryimage"},"thumbnailUrl":"https:\/\/t03.divertarte.com\/wp-content\/uploads\/2020\/01\/glicerina-branca-250g..jpg","datePublished":"2020-01-12T17:16:02+00:00","dateModified":"2023-10-10T15:43:27+00:00","description":"Glicerina para Sabonetes vegetal base Branca 250 g. Base de Glicerina Branca em Portugal Glicerina vegetal para sabonetes, Glicerina s\u00f3lida","breadcrumb":{"@id":"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/#primaryimage","url":"https:\/\/t03.divertarte.com\/wp-content\/uploads\/2020\/01\/glicerina-branca-250g..jpg","contentUrl":"https:\/\/t03.divertarte.com\/wp-content\/uploads\/2020\/01\/glicerina-branca-250g..jpg","width":400,"height":400,"caption":"glicerina para sabonetes"},{"@type":"BreadcrumbList","@id":"https:\/\/t03.divertarte.com\/index.php\/produto\/glicerina-branca-para-sabonetes-250-gr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/t03.divertarte.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/t03.divertarte.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Glicerina Branca para sabonetes 250 gr"}]},{"@type":"WebSite","@id":"https:\/\/t03.divertarte.com\/#website","url":"https:\/\/t03.divertarte.com\/","name":"Divertarte","description":"","publisher":{"@id":"https:\/\/t03.divertarte.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/t03.divertarte.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/t03.divertarte.com\/#organization","name":"Divertarte","url":"https:\/\/t03.divertarte.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/t03.divertarte.com\/#\/schema\/logo\/image\/","url":"https:\/\/t03.divertarte.com\/wp-content\/uploads\/2018\/07\/logo-div.jpg","contentUrl":"https:\/\/t03.divertarte.com\/wp-content\/uploads\/2018\/07\/logo-div.jpg","width":295,"height":123,"caption":"Divertarte"},"image":{"@id":"https:\/\/t03.divertarte.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/t03.divertarte.com\/index.php\/wp-json\/wp\/v2\/product\/9908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/t03.divertarte.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/t03.divertarte.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/t03.divertarte.com\/index.php\/wp-json\/wp\/v2\/comments?post=9908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/t03.divertarte.com\/index.php\/wp-json\/wp\/v2\/media\/9909"}],"wp:attachment":[{"href":"https:\/\/t03.divertarte.com\/index.php\/wp-json\/wp\/v2\/media?parent=9908"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/t03.divertarte.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=9908"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/t03.divertarte.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=9908"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/t03.divertarte.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=9908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}